{"id":2070,"date":"2024-08-04T11:25:20","date_gmt":"2024-08-04T11:25:20","guid":{"rendered":"https:\/\/kimamasr.com\/?page_id=2070"},"modified":"2024-08-05T10:45:53","modified_gmt":"2024-08-05T10:45:53","slug":"%d8%a7%d9%84%d9%85%d9%88%d8%a7%d8%af-%d8%a7%d9%84%d8%ae%d8%a7%d9%85","status":"publish","type":"page","link":"https:\/\/kimamasr.com\/ar\/%d8%a7%d9%84%d9%85%d9%88%d8%a7%d8%af-%d8%a7%d9%84%d8%ae%d8%a7%d9%85\/","title":{"rendered":"\u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u062e\u0627\u0645"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2070\" class=\"elementor elementor-2070 elementor-1916\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9734e3 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle ua-conditional-content-off\" data-id=\"b9734e3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d32a4ff\" data-id=\"d32a4ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87421c8 elementor-widget elementor-widget-heading\" data-id=\"87421c8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u062e\u0627\u0645<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fe9bfa elementor-section-boxed elementor-section-height-default elementor-section-height-default ua-conditional-content-off\" data-id=\"5fe9bfa\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-beb8edf\" data-id=\"beb8edf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21003f8 elementor-widget elementor-widget-elementskit-gallery\" data-id=\"21003f8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_gallery_columns&quot;:&quot;3&quot;,&quot;ekit_gallery_columns_tablet&quot;:&quot;2&quot;,&quot;ekit_gallery_columns_mobile&quot;:&quot;1&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >                        <div class=\"ekit_gallery_grid_wraper\"><div id=\"ekit_gallery_21003f8\" class=\"ekit_gallery_grid\" data-tilt-config=\"{&quot;disableAxis&quot;:null,&quot;easing&quot;:&quot;cubic-bezier(.03, .98, .52, .99)&quot;,&quot;glare&quot;:false,&quot;transition&quot;:true}\" data-masonry-config=\"{&quot;itemSelector&quot;:&quot;.ekit_gallery_grid_item&quot;}\">                                <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130955_20_11zon_20_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130832_17_11zon_17_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130819_16_11zon_16_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130608_14_11zon_14_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130557_13_11zon_13_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130423_11_11zon_11_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130403_10_11zon_10_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130402_9_11zon_9_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130339_8_11zon_8_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130130_6_11zon_6_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_130109_5_11zon_5_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_125412_1_11zon_1_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_132954_35_11zon_35_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_132925_34_11zon_34_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_132852_33_11zon_33_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n                            <div class=\"ekit_gallery_grid_item ekit_gallery__filter- \">\n                    <div class=\"elementskit-single-portfolio-item \"\n                                        >\n                        <div class=\"elementskit-portfolio-thumb\"\n                                                >\n                        <img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/kimamasr.com\/wp-content\/uploads\/2024\/08\/IMG_20240804_132704_31_11zon_31_11zon.jpg\" alt=\"gallery grid image\"\/>\n                        <\/div>\n                        <div class=\"elementskit-hover-area\">\n                            <div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n                                                                                                                                                            <\/div>\n                        <\/div><!-- .elementskit-hover-area END -->\n                                                <div class=\"ekit-gallery-image-overlay\"><\/div>\n                                            <\/div><!-- .elementskit-single-portfolio-item END -->\n                <\/div>\n\n                                                \n            <\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u062e\u0627\u0645<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2070","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/pages\/2070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/comments?post=2070"}],"version-history":[{"count":5,"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/pages\/2070\/revisions"}],"predecessor-version":[{"id":2116,"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/pages\/2070\/revisions\/2116"}],"wp:attachment":[{"href":"https:\/\/kimamasr.com\/ar\/wp-json\/wp\/v2\/media?parent=2070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}